{"id":14254,"date":"2023-07-12T10:28:20","date_gmt":"2023-07-12T10:28:20","guid":{"rendered":"https:\/\/www.cineturismofvg.com\/entdecken-sie-udine-mit-dem-far-east-film-festival\/"},"modified":"2023-07-12T10:28:21","modified_gmt":"2023-07-12T10:28:21","slug":"entdecken-sie-udine-mit-dem-far-east-film-festival","status":"publish","type":"post","link":"https:\/\/www.cineturismofvg.com\/de\/entdecken-sie-udine-mit-dem-far-east-film-festival\/","title":{"rendered":"Entdecken Sie Udine mit dem Far East Film Festival"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"14254\" class=\"elementor elementor-14254 elementor-13542\" data-elementor-post-type=\"post\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-ac07429 elementor-section-boxed elementor-section-height-default elementor-section-height-default sc_fly_static\" data-id=\"ac07429\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-extended\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-fc6a002 sc_content_align_inherit sc_layouts_column_icons_position_left sc_fly_static\" data-id=\"fc6a002\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f0c2194 sc_fly_static elementor-widget elementor-widget-text-editor\" data-id=\"f0c2194\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div><strong>Vom 21. bis 29. April 2023<\/strong> kehrt das gr\u00f6\u00dfte europ\u00e4ische Festival, das dem popul\u00e4ren Kino aus dem <strong>Fernen Osten<\/strong> gewidmet ist, nach <strong>Udine<\/strong> zur\u00fcck: das <strong>Far East Film Festival<\/strong>.<\/div>\n<div>In diesem Jahr werden <strong>78 Filme<\/strong> gezeigt: 9 Weltpremieren, 13 internationale, 14 europ\u00e4ische und 23 italienische.<\/div>\n<div>Drei Kultregisseure werden \u00fcber den roten Teppich schreiten: <strong>Johnnie To<\/strong> aus Hongkong, <strong>Watanabe Hirobumi<\/strong> aus Japan und <strong>Jang Sun-woo<\/strong> aus Korea. Die legend\u00e4re japanische Schauspielerin <strong>Baisho Chieko<\/strong> wird mit dem Gelso d&#8217;Oro alla Carriera ausgezeichnet.<\/div>\n<div>Ein Besuch in <strong>Udine,<\/strong> der Stadt des Tiepolo, wird so zu einer Gelegenheit f\u00fcr Filmliebhaber und Fans der <strong>asiatischen Welt<\/strong>. Neun Tage lang finden im Herzen der Stadt neben den Filmen zahlreiche Nebenveranstaltungen statt: Die mit Spannung erwartete Veranstaltung ist der <strong>Far East Cosplay Contest<\/strong>, der am <strong>Montag, den 24. April<\/strong> stattfindet.<\/div>\n<div>Eine Vorschau auf das <strong>Programm<\/strong> der 25. Ausgabe des Far East Film Festival finden Sie unter folgendem <strong>Link<\/strong>\u00a0&gt;&gt;&gt;\u00a0 https:\/\/www.fareastfilm.com\/notizie\/all-the-films-6440\/<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Ein Besuch in der Stadt des Tiepolo anl\u00e4sslich der 25. Ausgabe des Filmfestivals des Fernen Ostens kann eine einzigartige und unterhaltsame Gelegenheit sein. Das vollst\u00e4ndige Programm der Veranstaltung, die vom 21. bis 29. April 2023 in Udine stattfinden wird, steht bereit.<\/p>\n","protected":false},"author":4,"featured_media":11716,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[330],"tags":[],"class_list":["post-14254","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news-de"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.cineturismofvg.com\/de\/wp-json\/wp\/v2\/posts\/14254","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.cineturismofvg.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cineturismofvg.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cineturismofvg.com\/de\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cineturismofvg.com\/de\/wp-json\/wp\/v2\/comments?post=14254"}],"version-history":[{"count":1,"href":"https:\/\/www.cineturismofvg.com\/de\/wp-json\/wp\/v2\/posts\/14254\/revisions"}],"predecessor-version":[{"id":14255,"href":"https:\/\/www.cineturismofvg.com\/de\/wp-json\/wp\/v2\/posts\/14254\/revisions\/14255"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.cineturismofvg.com\/de\/wp-json\/wp\/v2\/media\/11716"}],"wp:attachment":[{"href":"https:\/\/www.cineturismofvg.com\/de\/wp-json\/wp\/v2\/media?parent=14254"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cineturismofvg.com\/de\/wp-json\/wp\/v2\/categories?post=14254"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cineturismofvg.com\/de\/wp-json\/wp\/v2\/tags?post=14254"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}